{"id":3335,"count":1,"description":"","link":"https:\/\/restlesspilgrim.net\/blog\/tag\/literature\/","name":"Literature","slug":"literature","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/tags\/3335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/posts?tags=3335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}