{"id":60055,"date":"2016-01-01T07:00:33","date_gmt":"2016-01-01T14:00:33","guid":{"rendered":"http:\/\/restlesspilgrim.net\/blog\/?p=60055"},"modified":"2015-12-30T17:04:40","modified_gmt":"2015-12-31T00:04:40","slug":"ewok-witnesses","status":"publish","type":"post","link":"https:\/\/restlesspilgrim.net\/blog\/2016\/01\/01\/ewok-witnesses\/","title":{"rendered":"Friday Frivolity: Ewok Witnesses"},"content":{"rendered":"<p><a href=\"http:\/\/restlesspilgrim.net\/blog\/wp-content\/uploads\/2015\/11\/Ewok.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60056\" src=\"http:\/\/restlesspilgrim.net\/blog\/wp-content\/uploads\/2015\/11\/Ewok.jpg\" alt=\"Ewok\" width=\"700\" height=\"698\" srcset=\"https:\/\/restlesspilgrim.net\/blog\/wp-content\/uploads\/2015\/11\/Ewok.jpg 700w, https:\/\/restlesspilgrim.net\/blog\/wp-content\/uploads\/2015\/11\/Ewok-150x150.jpg 150w, https:\/\/restlesspilgrim.net\/blog\/wp-content\/uploads\/2015\/11\/Ewok-300x300.jpg 300w, https:\/\/restlesspilgrim.net\/blog\/wp-content\/uploads\/2015\/11\/Ewok-600x598.jpg 600w, https:\/\/restlesspilgrim.net\/blog\/wp-content\/uploads\/2015\/11\/Ewok-90x90.jpg 90w, https:\/\/restlesspilgrim.net\/blog\/wp-content\/uploads\/2015\/11\/Ewok-75x75.jpg 75w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18],"tags":[3465,3464,3466,2875,3463,1589,2909],"class_list":["post-60055","post","type-post","status-publish","format-standard","hentry","category-humour","tag-awake","tag-c3po","tag-door-to-door","tag-evangelist","tag-ewok","tag-jehovah-witnesses","tag-jw"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/posts\/60055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/comments?post=60055"}],"version-history":[{"count":1,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/posts\/60055\/revisions"}],"predecessor-version":[{"id":60057,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/posts\/60055\/revisions\/60057"}],"wp:attachment":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/media?parent=60055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/categories?post=60055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/tags?post=60055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}