{"id":3746,"date":"2012-01-01T07:00:50","date_gmt":"2012-01-01T14:00:50","guid":{"rendered":"http:\/\/restlesspilgrim.net\/blog\/?p=3746"},"modified":"2011-10-08T15:45:47","modified_gmt":"2011-10-08T22:45:47","slug":"resolutions","status":"publish","type":"post","link":"https:\/\/restlesspilgrim.net\/blog\/2012\/01\/01\/resolutions\/","title":{"rendered":"Resolutions"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"facebook\" src=\"http:\/\/restlesspilgrim.net\/blog\/wp-content\/uploads\/2011\/10\/resolution-150x150.png\" alt=\"\" width=\"150\" height=\"150\" \/>For all of you who are starting your New Year&#8217;s Resolutions today&#8230;<\/p>\n<p style=\"text-align: center\"><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/PbMOnyeVE-4?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-US&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>For all of you who are starting your New Year&#8217;s Resolutions today&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17],"tags":[106],"class_list":["post-3746","post","type-post","status-publish","format-standard","hentry","category-faith","tag-new-year-resolution"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/posts\/3746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/comments?post=3746"}],"version-history":[{"count":4,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/posts\/3746\/revisions"}],"predecessor-version":[{"id":6418,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/posts\/3746\/revisions\/6418"}],"wp:attachment":[{"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/media?parent=3746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/categories?post=3746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/restlesspilgrim.net\/blog\/wp-json\/wp\/v2\/tags?post=3746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}